{"id":912,"count":14,"description":"","link":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/","name":"ddnTG","slug":"ddntg-en","taxonomy":"category","parent":911,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ddnTG Archivi - Design Diffusion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ddnTG Archivi - Design Diffusion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Design Diffusion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/ddntv-en\\\/ddntg-en\\\/\",\"url\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/ddntv-en\\\/ddntg-en\\\/\",\"name\":\"ddnTG Archivi - Design Diffusion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/ddntv-en\\\/ddntg-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/ddntv-en\\\/ddntg-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ddnTV\",\"item\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/ddntv-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ddnTG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/\",\"name\":\"Design Diffusion\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#organization\",\"name\":\"Design Diffusion\",\"url\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/designdiffusion.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-LOGO.webp\",\"contentUrl\":\"https:\\\/\\\/designdiffusion.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/cropped-LOGO.webp\",\"width\":254,\"height\":94,\"caption\":\"Design Diffusion\"},\"image\":{\"@id\":\"https:\\\/\\\/designdiffusion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ddnTG Archivi - Design Diffusion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/","og_locale":"en_US","og_type":"article","og_title":"ddnTG Archivi - Design Diffusion","og_url":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/","og_site_name":"Design Diffusion","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/","url":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/","name":"ddnTG Archivi - Design Diffusion","isPartOf":{"@id":"https:\/\/designdiffusion.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/designdiffusion.com\/en\/ddntv-en\/ddntg-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/designdiffusion.com\/en\/"},{"@type":"ListItem","position":2,"name":"ddnTV","item":"https:\/\/designdiffusion.com\/en\/ddntv-en\/"},{"@type":"ListItem","position":3,"name":"ddnTG"}]},{"@type":"WebSite","@id":"https:\/\/designdiffusion.com\/en\/#website","url":"https:\/\/designdiffusion.com\/en\/","name":"Design Diffusion","description":"","publisher":{"@id":"https:\/\/designdiffusion.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/designdiffusion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/designdiffusion.com\/en\/#organization","name":"Design Diffusion","url":"https:\/\/designdiffusion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/designdiffusion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/designdiffusion.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO.webp","contentUrl":"https:\/\/designdiffusion.com\/wp-content\/uploads\/2023\/07\/cropped-LOGO.webp","width":254,"height":94,"caption":"Design Diffusion"},"image":{"@id":"https:\/\/designdiffusion.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/designdiffusion.com\/en\/wp-json\/wp\/v2\/categories\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/designdiffusion.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/designdiffusion.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/designdiffusion.com\/en\/wp-json\/wp\/v2\/categories\/911"}],"wp:post_type":[{"href":"https:\/\/designdiffusion.com\/en\/wp-json\/wp\/v2\/posts?categories=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}